{"id":491,"date":"2006-06-23T01:00:45","date_gmt":"2006-06-22T23:00:45","guid":{"rendered":"https:\/\/news.lamprecht.net\/?p=491"},"modified":"2006-06-18T16:00:11","modified_gmt":"2006-06-18T14:00:11","slug":"gute-gewohnheiten-mit-dem-internet-erreichen-joes-goals","status":"publish","type":"post","link":"https:\/\/news.lamprecht.net\/index.php\/2006\/06\/23\/gute-gewohnheiten-mit-dem-internet-erreichen-joes-goals\/","title":{"rendered":"Gute Gewohnheiten mit dem Internet erreichen: Joe&#8217;s Goals"},"content":{"rendered":"<p><a href=\"http:\/\/www.43things.com\">43things<\/a> geh\u00f6rt immer noch zu meinem Lieblingsanwendungen der Web2.0-Bewegung. Ein Schwachpunkt des Dienstes aus meiner Sicht ist allerdings das Fehlen einer Dokumentation der Fortschritte auf ein Ziel zu. Zwar kann ich zu jedem meiner Ziele regelm\u00e4\u00dfige Erinnerungsmails einrichten und \u00fcber die Blogfunktion auch eine Art Tagebuch f\u00fchren. Es gibt aber keine kalendarische \u00dcbersicht. Anders geht <a href=\"http:\/\/www.joesgoals.com\">Joe&#8217;s Goals<\/a> vor. Unter einer recht schlichten Oberfl\u00e4che definieren Sie Ihre pers\u00f6nlichen Ziele, die mittels Tags organisiert werden. <\/p>\n<p><a href=\"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/images\/joegoal.jpg?ssl=1\" title=\"Joe&#8217;s Goals\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/images\/thumb-joegoal.jpg?resize=400%2C202&#038;ssl=1\" width=\"400\" height=\"202\" alt=\"Joe&#8217;s Goals\" \/><\/a><\/p>\n<p>Zu jedem der Ziele legen Sie fest, an welchen Tagen Sie es erreichen wollen. Durch einfaches Anklicken des jeweiligen Tages verfolgen Sie somit, ob Sie das Ziel an diesem Tag erreicht haben. Damit bietet sich Joe&#8217;s Goals besonders zum Ein\u00fcben neuer Gewohnheiten an. Den Fortschritt Ihrer Zielerreichung d\u00fcrfen Sie auch mit anderen teilen. Dazu benachrichtigen Sie Ihre Freunde oder Partner per E-Mail direkt aus dem System heraus. Am Ende der verschickten Mail erhalten die Empf\u00e4nger einen Link, der zur \u00dcbersicht der Fortschritte f\u00fchrt.<\/p>\n<p>Verbl\u00fcffend einfach, verbl\u00fcffend effektiv: Joe&#8217;s Goals<\/p>\n","protected":false},"excerpt":{"rendered":"<p>43things geh\u00f6rt immer noch zu meinem Lieblingsanwendungen der Web2.0-Bewegung. Ein Schwachpunkt des Dienstes aus meiner Sicht ist allerdings das Fehlen einer Dokumentation der Fortschritte auf ein Ziel zu. Zwar kann ich zu jedem meiner Ziele regelm\u00e4\u00dfige Erinnerungsmails einrichten und \u00fcber die Blogfunktion auch eine Art Tagebuch f\u00fchren. Es gibt aber keine kalendarische \u00dcbersicht. Anders geht &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/news.lamprecht.net\/index.php\/2006\/06\/23\/gute-gewohnheiten-mit-dem-internet-erreichen-joes-goals\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eGute Gewohnheiten mit dem Internet erreichen: Joe&#8217;s Goals\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[10,14,15],"class_list":["post-491","post","type-post","status-publish","format-aside","hentry","tag-selbstmanagement","tag-socialsoftware","tag-web-20","post_format-post-format-aside"],"wppr_data":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOKED-7V","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":116,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/04\/01\/was-sind-43-dinge-die-sie-tun-mochten\/","url_meta":{"origin":491,"position":0},"title":"Was sind 43 Dinge, die Sie tun m\u00f6chten?","author":"Stephan Lamprecht, Ahrensburg","date":"1\/4\/2005","format":"aside","excerpt":"Beim Erreichen Ihrer Ziele m\u00f6chte Sie eine Gemeinschaft im WWW unterst\u00fctzen, die auf den Namen \"43 Things\":http:\/\/www.43things.com geh\u00f6rt. Wie viele erfolgreiche Ideen im Internet ist das Konzept des Dienstes einfach zu beschreiben: Sie legen dort eine Liste von Zielen an, die Sie erreichen wollen. Diese Liste ist \u00f6ffentlich und kann\u2026","rel":"","context":"In \"Bookmarks\"","block_context":{"text":"Bookmarks","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/bookmarks\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":199,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/05\/27\/apropos-ziele\/","url_meta":{"origin":491,"position":1},"title":"Apropos: Ziele","author":"Stephan Lamprecht, Ahrensburg","date":"27\/5\/2005","format":"aside","excerpt":"Das Jahr n\u00e4hert sich unerbittlich seiner Mitte: H\u00f6chste Zeit also, die eigenen Zielsetzungen zu \u00fcberpr\u00fcfen. Sind Sie noch auf dem Weg zu Ihrem gew\u00fcnschten Ziel? Oder hat Sie die Tagesroutine von der Verfolgung Ihres Weges abgehalten? Die Mitte des Jahres wird in vielen Unternehmen zu einer \u00e4hnlichen R\u00fcck- und Vorschau\u2026","rel":"","context":"In \"Selbstmanagement\"","block_context":{"text":"Selbstmanagement","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/selbstmanagement\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1305,"url":"https:\/\/news.lamprecht.net\/index.php\/2009\/03\/16\/zielplanung-mit-goalenforcer-hyperfocus\/","url_meta":{"origin":491,"position":2},"title":"Zielplanung mit GoalEnforcer Hyperfocus","author":"Stephan Lamprecht, Ahrensburg","date":"16\/3\/2009","format":"aside","excerpt":"Glaubt man den Aussagen des Herstellers, haben Sie kaum eine andere Wahl Ihre pers\u00f6nlichen Ziele zu erreichen, als zu GoalEnforcer zu greifen. Das zwischen 9 und knapp 70 Dollar teure Werkzeug kommt mit einer recht \u00fcberschaubaren Oberfl\u00e4che daher und erinnert an einen Mindmapper, ohne dessen grafischen Gestaltungsoptionen anzubieten. Im Zentrum\u2026","rel":"","context":"In &quot;allgemein&quot;","block_context":{"text":"allgemein","link":"https:\/\/news.lamprecht.net\/index.php\/category\/stamm\/allgemein\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/uploads\/goalenforcer2-small.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1287,"url":"https:\/\/news.lamprecht.net\/index.php\/2009\/02\/24\/springpad-ein-wiki-das-ihnen-beim-selbstmanagement-hilft\/","url_meta":{"origin":491,"position":3},"title":"Springpad: Ein Wiki, das Ihnen beim Selbstmanagement hilft","author":"Stephan Lamprecht, Ahrensburg","date":"24\/2\/2009","format":"aside","excerpt":"Wikis eignen sich dank ihrer Vielschichtigkeit perfekt f\u00fcr die Selbstorganisation: Sei es zum Notieren von Einkaufs- und Aufgabenlisten, zur Projektdokumentation oder auch als Zettelkasten. Gerade Einsteiger tun sich allerdings mit dieser Vielschichtigkeit mitunter schwer. Abhilfe verspricht hier der Dienst Springpad. Die Er\u00f6ffnung eines Benutzerkontos bei Springpad ist kostenlos. Nachdem Sie\u2026","rel":"","context":"In &quot;allgemein&quot;","block_context":{"text":"allgemein","link":"https:\/\/news.lamprecht.net\/index.php\/category\/stamm\/allgemein\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/uploads\/springpad-2-small.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1404,"url":"https:\/\/news.lamprecht.net\/index.php\/2009\/04\/30\/onepoint-project-exzellente-projektsoftware\/","url_meta":{"origin":491,"position":4},"title":"Onepoint Project &#8211; exzellente Projektsoftware","author":"Stephan Lamprecht, Ahrensburg","date":"30\/4\/2009","format":"aside","excerpt":"Mit Onepoint m\u00f6chte ich Ihnen heute eine noch weithin unbekannte Software f\u00fcr das Projektmanagement vorstellen, die den Vorzug besitzt, sowohl f\u00fcr Windows als auch Linux angeboten zu werden. Das in Java geschriebene Programm ist einfach zu installieren. Nach dem ersten Start blicken Sie auf eine sehr aufger\u00e4umt wirkende Oberfl\u00e4che, die\u2026","rel":"","context":"In &quot;allgemein&quot;","block_context":{"text":"allgemein","link":"https:\/\/news.lamprecht.net\/index.php\/category\/stamm\/allgemein\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/uploads\/onepoint-2-small.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":253,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/07\/26\/ihr-werkzeug-muss-zu-ihnen-passen-nicht-umgekehrt\/","url_meta":{"origin":491,"position":5},"title":"Ihr Werkzeug muss zu Ihnen passen &#8211; nicht umgekehrt","author":"Stephan Lamprecht, Ahrensburg","date":"26\/7\/2005","format":"aside","excerpt":"Meine Tipps zur Einrichtung eines Zeitplanbuchs..","rel":"","context":"In \"Selbstmanagement\"","block_context":{"text":"Selbstmanagement","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/selbstmanagement\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts\/491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/comments?post=491"}],"version-history":[{"count":0,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts\/491\/revisions"}],"wp:attachment":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/media?parent=491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/categories?post=491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/tags?post=491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}