{"id":465,"date":"2006-05-08T01:00:23","date_gmt":"2006-05-08T00:00:23","guid":{"rendered":"https:\/\/news.lamprecht.net\/?p=465"},"modified":"2006-05-06T13:38:59","modified_gmt":"2006-05-06T12:38:59","slug":"sudoku-online-spielen","status":"publish","type":"post","link":"https:\/\/news.lamprecht.net\/index.php\/2006\/05\/08\/sudoku-online-spielen\/","title":{"rendered":"Sudoku online spielen"},"content":{"rendered":"<p>In R\u00e4tselheften und Tageszeitungen haben sich Sudokus inzwischen einen festen Platz erobert. Die s\u00fcchtig machenden kleinen Zahlenspielereien k\u00f6nnen vielerorts auch im Web gespielt werden. Mir pers\u00f6nlich hat in Optik und Bedienung <a href=\"http:\/\/www.sudokucraving.com\">Sudokucraving <\/a>gefallen. <\/p>\n<p>Jeden Tag gibt es neue R\u00e4tsel in unterschiedlichen Schwierigkeitsgraden und die Installation eines Plugins ist f\u00fcr das Spiel nicht n\u00f6tig. Zur Speicherung pers\u00f6nlicher Statistiken ben\u00f6tigen Sie ein kostenloses Benutzerkonto, das binnen zwei Minuten eingerichtet ist. <\/p>\n<p><a href=\"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/images\/sudoku.jpg?ssl=1\" title=\"Sudokucraving in Aktion\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/images\/thumb-sudoku.jpg?resize=400%2C370&#038;ssl=1\" width=\"400\" height=\"370\" alt=\"Sudokucraving in Aktion\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In R\u00e4tselheften und Tageszeitungen haben sich Sudokus inzwischen einen festen Platz erobert. Die s\u00fcchtig machenden kleinen Zahlenspielereien k\u00f6nnen vielerorts auch im Web gespielt werden. Mir pers\u00f6nlich hat in Optik und Bedienung Sudokucraving gefallen. Jeden Tag gibt es neue R\u00e4tsel in unterschiedlichen Schwierigkeitsgraden und die Installation eines Plugins ist f\u00fcr das Spiel nicht n\u00f6tig. Zur Speicherung &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/news.lamprecht.net\/index.php\/2006\/05\/08\/sudoku-online-spielen\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eSudoku online spielen\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[6],"class_list":["post-465","post","type-post","status-publish","format-aside","hentry","tag-bookmarks","post_format-post-format-aside"],"wppr_data":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOKED-7v","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1738,"url":"https:\/\/news.lamprecht.net\/index.php\/2010\/01\/06\/meine-ersten-zwei-wochen-mit-dem-htc-tattoo\/","url_meta":{"origin":465,"position":0},"title":"Meine ersten zwei Wochen mit dem HTC Tattoo","author":"Stephan Lamprecht, Ahrensburg","date":"6\/1\/2010","format":"aside","excerpt":"Nachdem sich Michael vor einigen Wochen das Android-Handy HTC Tattoo zugelegt hatte, dauerte mein Neidfaktor gerade einmal wenige Tage und schon habe ich meinen Vodafone Vertrag vorzeitig verl\u00e4ngert und mir das Handy f\u00fcr 1 Euro gesichert. Nach zwei Wochen ist es an der Zeit, ein erstes Fazit zu ziehen. Das\u2026","rel":"","context":"In &quot;allgemein&quot;","block_context":{"text":"allgemein","link":"https:\/\/news.lamprecht.net\/index.php\/category\/stamm\/allgemein\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2085,"url":"https:\/\/news.lamprecht.net\/index.php\/2011\/03\/03\/satteln-sie-um-herr-rumohr-meine-replik-auf-das-lobhudeln-von-xing\/","url_meta":{"origin":465,"position":1},"title":"Satteln Sie um Herr Rumohr: Meine Replik auf das Lobhudeln von XING","author":"Stephan Lamprecht, Ahrensburg","date":"3\/3\/2011","format":false,"excerpt":"Warten wir es ab, bis die Trolle und N\u00f6rgler ein anderes Ziel gefunden haben und schauen uns dann an, wie das Feedback der XING-Seminar-Teilnehmer und aktiven Mitglieder ist, die XING wirklich nutzen wollen und einen solchen auch darin sehen. Dies ist f\u00fcr mich im Zweifelsfall viel wichtiger. via rumohr.de Wenn\u2026","rel":"","context":"In &quot;allgemein&quot;","block_context":{"text":"allgemein","link":"https:\/\/news.lamprecht.net\/index.php\/category\/stamm\/allgemein\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2128,"url":"https:\/\/news.lamprecht.net\/index.php\/2011\/06\/02\/die-zukunft-des-lesens-ist-digital-das-dauert-noch-glauben-sie-mir\/","url_meta":{"origin":465,"position":2},"title":"Die Zukunft des Lesens ist digital? Das dauert noch, glauben Sie mir","author":"Stephan Lamprecht, Ahrensburg","date":"2\/6\/2011","format":false,"excerpt":"Amazon will nach eigenem Bekunden inzwischen mehr elektronische als klassische B\u00fccher verkaufen. Das klingt beeindruckend, oder? Bedeutet das nun, dass die digitale Zukunft des Lesens gekommen ist? Ich glaube nicht. Warum? Weil Sie ein Buch einfach aus dem Regal nehmen und \u00fcberall lesen k\u00f6nnen! Und Sie k\u00f6nnen es auch jedem\u2026","rel":"","context":"In &quot;allgemein&quot;","block_context":{"text":"allgemein","link":"https:\/\/news.lamprecht.net\/index.php\/category\/stamm\/allgemein\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1083,"url":"https:\/\/news.lamprecht.net\/index.php\/2008\/07\/16\/openoffice-und-google-docs-synchron-halten\/","url_meta":{"origin":465,"position":3},"title":"OpenOffice und Google Docs synchron halten","author":"Stephan Lamprecht, Ahrensburg","date":"16\/7\/2008","format":"aside","excerpt":"Dank Gears k\u00f6nnen Sie ja an Ihren Office-Dokumenten, die Sie bei Google gespeichert haben, selbst dann weiterarbeiten, wenn keine Verbindung zum Internet besteht. Ich pers\u00f6nlich habe mich aber an zahlreiche Shortcuts und meine Autotexte in OpenOffice so gew\u00f6hnt, dass ich umfangreichere Arbeiten lieber mit diesem Programm bearbeite, dennoch aber auf\u2026","rel":"","context":"In \"OpenOffice\"","block_context":{"text":"OpenOffice","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/openoffice\/"},"img":{"alt_text":"docsyncer","src":"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/images\/docsyncer-small-20080713132906.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2145,"url":"https:\/\/news.lamprecht.net\/index.php\/2011\/06\/24\/einfacher-gemeinsam-schenken-simple-present\/","url_meta":{"origin":465,"position":4},"title":"Einfacher gemeinsam Schenken &#8211; Simple Present","author":"Stephan Lamprecht, Ahrensburg","date":"24\/6\/2011","format":false,"excerpt":"Was schenken wir eigentlich...? Anl\u00e4sse gemeinsam als Gruppe einer Person etwas zu schenken, gibt es ja reichlich. Runde Geburtstage, Hochzeiten, Einweihungen und und und. Aber der Weg zum Geschenk ist ja h\u00e4ufig zeitraubend und vor allem steinig. Ideen m\u00fcssen gefunden werden, die dann auch noch die Mitschenkenden \u00fcberzeugen. Au\u00dferdem ist\u2026","rel":"","context":"In &quot;allgemein&quot;","block_context":{"text":"allgemein","link":"https:\/\/news.lamprecht.net\/index.php\/category\/stamm\/allgemein\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3831,"url":"https:\/\/news.lamprecht.net\/index.php\/2026\/01\/10\/dieser-ddr-roman-hat-mich-bis-in-die-morgenstunden-wachgehalten\/","url_meta":{"origin":465,"position":5},"title":"Dieser DDR-Roman hat mich bis in die Morgenstunden wachgehalten","author":"Stephan Lamprecht, Ahrensburg","date":"10\/1\/2026","format":false,"excerpt":"Es ist schon verdammt lange her, dass mich ein Buch derart in seinen Bann gezogen hat. \u00abZwei, drei blaue Augen\u00bb von Victor Schef\u00e9 ist einer dieser seltenen Pageturner, bei denen man das Licht erst in den fr\u00fchen Morgenstunden ausknipst \u2013 nicht, weil man es sollte, sondern weil man einfach nicht\u2026","rel":"","context":"In &quot;allgemein&quot;","block_context":{"text":"allgemein","link":"https:\/\/news.lamprecht.net\/index.php\/category\/stamm\/allgemein\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/uploads\/zwei-drei-blaue-augen-1.jpg?fit=514%2C749&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts\/465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/comments?post=465"}],"version-history":[{"count":0,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts\/465\/revisions"}],"wp:attachment":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/media?parent=465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/categories?post=465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/tags?post=465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}