{"id":316,"date":"2005-09-22T01:20:55","date_gmt":"2005-09-21T23:20:55","guid":{"rendered":"https:\/\/news.lamprecht.net\/?p=316"},"modified":"2005-09-23T15:53:25","modified_gmt":"2005-09-23T13:53:25","slug":"computer-des-tages","status":"publish","type":"post","link":"https:\/\/news.lamprecht.net\/index.php\/2005\/09\/22\/computer-des-tages\/","title":{"rendered":"Computer des Tages?"},"content":{"rendered":"<p>Also mir ist ja auch bekannt, dass die Auszeichnungen der IT-Zeitschriften in immer k\u00fcrzeren Zyklen erscheinen, aber die Wahl zum t\u00e4glichen Computer halte ich denn doch f\u00fcr \u00fcbertrieben.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/images\/montagscomputer.jpg?resize=271%2C103&#038;ssl=1\" width=\"271\" height=\"103\" alt=\"Computer des Montags\" \/><br \/>\nGefunden bei Dell, an einem Donnerstag.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Also mir ist ja auch bekannt, dass die Auszeichnungen der IT-Zeitschriften in immer k\u00fcrzeren Zyklen erscheinen, aber die Wahl zum t\u00e4glichen Computer halte ich denn doch f\u00fcr \u00fcbertrieben. Gefunden bei Dell, an einem Donnerstag.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[4],"class_list":["post-316","post","type-post","status-publish","format-aside","hentry","tag-marginalia","post_format-post-format-aside"],"wppr_data":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOKED-56","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":158,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/05\/03\/das-war-aber-kurz-computer-aktuell-schon-wieder-eingestellt\/","url_meta":{"origin":316,"position":0},"title":"Das war aber kurz: Computer aktuell schon wieder eingestellt?","author":"Stephan Lamprecht, Ahrensburg","date":"3\/5\/2005","format":"aside","excerpt":"Da habe ich doch erst vor wenigen Tagen die neue Zeitung \"Computer aktuell\" \"vorgestellt\":https:\/\/news.lamprecht.net\/index.php\/04\/23\/computer-akuell-it-goes-boulevard\/, da scheint das Projekt von \"Carsten Scheibe\":http:\/\/www.typemania.de bereits wieder vor dem Aus zu stehen. Die immer gut informierte Ger\u00fcchtek\u00fcche der IT-Journalisten weiss zu berichten, dass die Absatzzahlen der Erstausgabe wohl weit hinter den Erwartungen zur\u00fcckgeblieben sind.\u2026","rel":"","context":"In \"Marginalia\"","block_context":{"text":"Marginalia","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/marginalia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":145,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/04\/23\/computer-akuell-it-goes-boulevard\/","url_meta":{"origin":316,"position":1},"title":"Computer akuell &#8211; IT goes Boulevard","author":"Stephan Lamprecht, Ahrensburg","date":"23\/4\/2005","format":"aside","excerpt":"\"Carsten Scheibe\":http:\/\/www.typemania.de fundierter Kenner der Shareware-Szene und mannigfaltig als Autor und Journalist unterwegs, hat ein neues Projekt gestemmt. \"Computer aktuell\" soll f\u00fcr 90 Cent alle 14 Tage neu am Kiosk liegen und wird auf Zeitungspapier gedruckt. Das Heft erinnert ein wenig an die vor einigen Jahren vom Vogel Verlag herausgegebene\u2026","rel":"","context":"In \"Marginalia\"","block_context":{"text":"Marginalia","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/marginalia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":661,"url":"https:\/\/news.lamprecht.net\/index.php\/2007\/01\/13\/links-for-2007-01-13\/","url_meta":{"origin":316,"position":2},"title":"links for 2007-01-13","author":"Stephan Lamprecht, Ahrensburg","date":"13\/1\/2007","format":"aside","excerpt":"In Pictures: Online computer tutorials based on pictures. Free. In Pictures online tutorials are based on pictures, not words. They're the easiest way to learn computer subjects. (tags: books tutorial howto referenz openoffice) FTD - In weiter Ferne so nah - Management Verbraucher tauschen sich im Internet zunehmend \u00fcber die\u2026","rel":"","context":"In \"Bookmarks\"","block_context":{"text":"Bookmarks","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/bookmarks\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1058,"url":"https:\/\/news.lamprecht.net\/index.php\/2008\/06\/17\/die-veraltete-technik-in-unternehmen-2\/","url_meta":{"origin":316,"position":3},"title":"Die veraltete Technik in Unternehmen","author":"Stephan Lamprecht, Ahrensburg","date":"17\/6\/2008","format":"aside","excerpt":"In einem Artikel der von mir sehr gesch\u00e4tzten Zeitschrift Business Technology, der sich mit der Investionsfreudigkeit in deutschen Unternehmen auseinandersetzt, habe ich einen nachdenkenswerten Satz gefunden. Dieser besagt, sinngem\u00e4\u00df zitiert, dass das Tempo der Erfahrung eines Mitarbeiters im Umgang mit IT heute vom privaten Umfeld dominiert wird. Online-Anwendungen aus dem\u2026","rel":"","context":"In \"Lekt\u00fcre\"","block_context":{"text":"Lekt\u00fcre","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/lektuere\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1142,"url":"https:\/\/news.lamprecht.net\/index.php\/2008\/10\/26\/links-for-2008-10-25\/","url_meta":{"origin":316,"position":4},"title":"links for 2008-10-25","author":"Stephan Lamprecht, Ahrensburg","date":"26\/10\/2008","format":"aside","excerpt":"brand eins Magazin - Inhalte Die Unternehmen werden immer effizienter, Mitarbeiter wie Vorgesetzte geraten immer st\u00e4rker unter Druck. Und f\u00fcr Anerkennung bleibt immer weniger Zeit. Effektiver kann man eine Organisation nicht sauer fahren. (tags: arbeitswelt effizienz management) 25 Jahre \u00e2\u20ac\u017ec't\u00e2\u20ac\u0153: M\u00e4nner, die alles genau wissen wollen - Computer & Internet\u2026","rel":"","context":"In \"Bookmarks\"","block_context":{"text":"Bookmarks","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/bookmarks\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1166,"url":"https:\/\/news.lamprecht.net\/index.php\/2008\/12\/28\/links-for-2008-12-27\/","url_meta":{"origin":316,"position":5},"title":"links for 2008-12-27","author":"Stephan Lamprecht, Ahrensburg","date":"28\/12\/2008","format":"aside","excerpt":"Netbook-Markt 2009: Lauter kleine Kannibalen - SPIEGEL ONLINE - Nachrichten - Netzwelt Die preiswerten, in ihrer Leistung limitierten Netbooks sind das Boom-Produkt des Jahres und der Trend f\u00fcr 2009. Weil das urspr\u00fcngliche Konzept ausgereizt ist, beginnt die Kannibalisierung anderer Marktsegmente. Nur Apple z\u00f6gert noch - als Firma, die deutlich mehr\u2026","rel":"","context":"In \"Bookmarks\"","block_context":{"text":"Bookmarks","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/bookmarks\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts\/316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/comments?post=316"}],"version-history":[{"count":0,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts\/316\/revisions"}],"wp:attachment":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/media?parent=316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/categories?post=316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/tags?post=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}