{"id":313,"date":"2005-09-19T06:55:43","date_gmt":"2005-09-19T04:55:43","guid":{"rendered":"https:\/\/news.lamprecht.net\/?p=313"},"modified":"2005-09-19T11:35:16","modified_gmt":"2005-09-19T09:35:16","slug":"besuchen-sie-einen-workshop-mit-mir","status":"publish","type":"post","link":"https:\/\/news.lamprecht.net\/index.php\/2005\/09\/19\/besuchen-sie-einen-workshop-mit-mir\/","title":{"rendered":"Besuchen Sie einen Workshop mit mir"},"content":{"rendered":"<p>So viel Zeit f\u00fcr schamlose Eigenreklame muss schon sein: Anfang November startet bei der <a href=\"http:\/\/www.workshopwelt.de\">Workshopwelt<\/a> ein Online-Seminar von mir. Das Thema: Suchen statt finden! <\/p>\n<p>In diesem Workshop zeige ich Ihnen, wie Sie im Internet wirklich die Informationen finden, die Sie gesucht haben, ohne im Datenmeer der Ergebnislisten von Google&#038;Co. zu ertrinken. Das Seminarprogramm finden Sie direkt bei der Workshopwelt<\/p>\n","protected":false},"excerpt":{"rendered":"<p>So viel Zeit f\u00fcr schamlose Eigenreklame muss schon sein: Anfang November startet bei der Workshopwelt ein Online-Seminar von mir. Das Thema: Suchen statt finden! In diesem Workshop zeige ich Ihnen, wie Sie im Internet wirklich die Informationen finden, die Sie gesucht haben, ohne im Datenmeer der Ergebnislisten von Google&#038;Co. zu ertrinken. Das Seminarprogramm finden Sie &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/news.lamprecht.net\/index.php\/2005\/09\/19\/besuchen-sie-einen-workshop-mit-mir\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eBesuchen Sie einen Workshop mit mir\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[4],"class_list":["post-313","post","type-post","status-publish","format-aside","hentry","tag-marginalia","post_format-post-format-aside"],"wppr_data":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOKED-53","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":84,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/03\/18\/entmullen-sie-den-ordner-gesendete-objekte\/","url_meta":{"origin":313,"position":0},"title":"Entm\u00fcllen Sie den Ordner &#8220;Gesendete Objekte&#8221;","author":"Stephan Lamprecht, Ahrensburg","date":"18\/3\/2005","format":"aside","excerpt":"Alle mir bekannten E-Mailprogramme sammeln Kopien geschriebener Nachrichten in einem Ordner, der Gesendete Objekte, Versandte Nachrichten o.\u00e4. hei\u00dft. Intensive Nutzer des Kommunikationsmittels E-Mail wissen, dass es sich bei diesem Ordner um einen nutzlosen Datenspeicher handelt. Bei mir liegen dort nach einem Jahr oftmals mehr als 3000 Elemente. Darin mal eben\u2026","rel":"","context":"In \"Selbstmanagement\"","block_context":{"text":"Selbstmanagement","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/selbstmanagement\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":342,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/10\/20\/wollen-sie-eine-suchmaschine-kaufen\/","url_meta":{"origin":313,"position":1},"title":"Wollen Sie eine Suchmaschine kaufen?","author":"Stephan Lamprecht, Ahrensburg","date":"20\/10\/2005","format":"aside","excerpt":"Wenn Sie schon immer einmal im Besitz einer eigenen Metasuchmaschine sein wollten, dann haben Sie jetzt die Gelegenheit. Jux2 versteigert gerade seine Suchtechnologie bei Ebay. Das aktuelle Gebot liegt derzeit bei rund 26.000 US-Dollar. In diesem Preis enthalten ist aber lediglich der Quellcode. F\u00fcr Server und Abkommen mit den Suchmaschinen\u2026","rel":"","context":"In \"Bookmarks\"","block_context":{"text":"Bookmarks","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/bookmarks\/"},"img":{"alt_text":"Homepage Jux2","src":"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/images\/thumb-jux2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":250,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/07\/21\/ihr-kriegt-das-web-schon-kaputt\/","url_meta":{"origin":313,"position":2},"title":"Ihr kriegt das Web schon kaputt","author":"Stephan Lamprecht, Ahrensburg","date":"21\/7\/2005","format":"aside","excerpt":"Herr Lamprecht hadert mit Suchmaschinenoptimierern...","rel":"","context":"In \"Blogging\"","block_context":{"text":"Blogging","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/blogging\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1253,"url":"https:\/\/news.lamprecht.net\/index.php\/2009\/02\/02\/dinge-im-griff-behalten-mit-todolist\/","url_meta":{"origin":313,"position":3},"title":"Dinge im Griff behalten mit ToDoList","author":"Stephan Lamprecht, Ahrensburg","date":"2\/2\/2009","format":"aside","excerpt":"Wie den Stammlesern dieses Blogs sicherlich bereits aufgefallen ist, probiere ich nur zu gern Programme aus, mit denen sich Aufgaben und Projekte verwalten lassen. An dieser Stelle noch nicht vorgestellt wurde ToDoList von AbstractSpoon, das Sie in einer kostenlosen Version f\u00fcr Windows auf Ihren Rechner laden d\u00fcrfen. Schon beim ersten\u2026","rel":"","context":"In &quot;allgemein&quot;","block_context":{"text":"allgemein","link":"https:\/\/news.lamprecht.net\/index.php\/category\/stamm\/allgemein\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/uploads\/todolist-1-small.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":380,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/12\/21\/hipcal-webbasierter-pim\/","url_meta":{"origin":313,"position":4},"title":"HipCal &#8211; webbasierter PIM","author":"Stephan Lamprecht, Ahrensburg","date":"21\/12\/2005","format":"aside","excerpt":"Mit HipCal steht ein neuer webbasierter PIM zur Verf\u00fcgung, der an Basecamp oder Remember The Milk erinnert.","rel":"","context":"In \"Bookmarks\"","block_context":{"text":"Bookmarks","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/bookmarks\/"},"img":{"alt_text":"Logo HipCal","src":"https:\/\/i0.wp.com\/news.lamprecht.net\/wp-content\/images\/hipcal2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":352,"url":"https:\/\/news.lamprecht.net\/index.php\/2005\/11\/04\/internet-world-business\/","url_meta":{"origin":313,"position":5},"title":"Internet World Business","author":"Stephan Lamprecht, Ahrensburg","date":"4\/11\/2005","format":"aside","excerpt":"Da liegen sie also vor mir. Die ersten beiden Ausgaben der Internet World Business. Erinnern Sie sich noch an den Net-Investor oder das ambitionierte Projekt \"Netbusiness\" von Klaus Madzia? Gl\u00fcckwunsch, dann geh\u00f6ren Sie zu den Veteranen der \"New Economy\" und waren live dabei, wie Millionen an Venture Capital sich in\u2026","rel":"","context":"In \"Marginalia\"","block_context":{"text":"Marginalia","link":"https:\/\/news.lamprecht.net\/index.php\/tag\/marginalia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":0,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"wp:attachment":[{"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.lamprecht.net\/index.php\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}